{"id":3458,"date":"2017-04-17T18:26:12","date_gmt":"2017-04-17T16:26:12","guid":{"rendered":"https:\/\/micasatucasaibiza.com\/?post_type=villas&#038;p=3458"},"modified":"2026-03-03T09:37:25","modified_gmt":"2026-03-03T08:37:25","slug":"can-tomas","status":"publish","type":"villas","link":"https:\/\/micasatucasaibiza.com\/es\/alquiler-villas-ibiza\/can-tomas\/","title":{"rendered":"Can Tomas"},"content":{"rendered":"<p>Saliendo del precioso pueblo de San Jos\u00e9 y siguiendo la angosta carretera hacia el oeste por el maravilloso campo durante 3 km se llega a Can Tom\u00e1s. La villa se ubica en una de las laderas de la colina y est\u00e1 rodeada por cultivos en terraza con olivos, algarrobos y almendros. Hay unas vistas preciosas al otro lado del valle de la iglesia de San Agust\u00edn as\u00ed como hacia el oeste, donde se encuentra, un poco m\u00e1s lejos, Cap Negret. Can Tom\u00e1s acaba de ser renovada con mucho estilo y es una peque\u00f1a joya que queremos ofrecer a nuestros hu\u00e9spedes. Es una magn\u00edfica casa para una familia o un peque\u00f1o grupo de amigos para relajarse y respirar la belleza de las zonas rurales de Ibiza.<\/p>","protected":false},"featured_media":17121,"template":"","meta":{"_acf_changed":false,"footnotes":""},"areas":[434],"bedrooms":[424],"sleeps":[440],"villa_tag":[471,472,466,467,487],"class_list":["post-3458","villas","type-villas","status-publish","has-post-thumbnail","hentry","areas-san-jose-hills","bedrooms-424","sleeps-440","villa_tag-ibiza-family-villas","villa_tag-ibiza-countryside-villas","villa_tag-ibiza-villas-with-sea-views","villa_tag-small-ibiza-villas-for-intimate-breaks","villa_tag-villas-in-ibiza-with-private-pool"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Villa de 3 dormitorios con piscina privada cerca de San Jos\u00e9<\/title>\n<meta name=\"description\" content=\"Can Tom\u00e1s es una villa rural en alquiler en Ibiza gestionada en exclusiva por Mi Casa Tu casa. Tiene 3 dormitorios, vistas al campo y piscina privada\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"\/es\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Villa de 3 dormitorios con piscina privada cerca de San Jos\u00e9\" \/>\n<meta property=\"og:description\" content=\"Can Tom\u00e1s es una villa rural en alquiler en Ibiza gestionada en exclusiva por Mi Casa Tu casa. Tiene 3 dormitorios, vistas al campo y piscina privada\" \/>\n<meta property=\"og:url\" content=\"\/es\/\" \/>\n<meta property=\"og:site_name\" content=\"Mi Casa Tu Casa Ibiza\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MiCasaTuCasaIbiza\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-03T08:37:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/micasatucasaibiza.com\/wp-content\/uploads\/2017\/04\/can-tomas-exterior-dining.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/micasatucasaibiza.com\\\/es\\\/ibiza-rental-villas\\\/can-tomas\\\/\",\"url\":\"\\\/es\\\/\",\"name\":\"Villa de 3 dormitorios con piscina privada cerca de San Jos\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/micasatucasaibiza.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"\\\/es\\\/#primaryimage\"},\"image\":{\"@id\":\"\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/micasatucasaibiza.com\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/can-tomas-exterior-dining.jpg\",\"datePublished\":\"2017-04-17T16:26:12+00:00\",\"dateModified\":\"2026-03-03T08:37:25+00:00\",\"description\":\"Can Tom\u00e1s es una villa rural en alquiler en Ibiza gestionada en exclusiva por Mi Casa Tu casa. Tiene 3 dormitorios, vistas al campo y piscina privada\",\"breadcrumb\":{\"@id\":\"\\\/es\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"\\\/es\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"\\\/es\\\/#primaryimage\",\"url\":\"https:\\\/\\\/micasatucasaibiza.com\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/can-tomas-exterior-dining.jpg\",\"contentUrl\":\"https:\\\/\\\/micasatucasaibiza.com\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/can-tomas-exterior-dining.jpg\",\"width\":2000,\"height\":1333,\"caption\":\"Can Tomas Exterior Dining\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"\\\/es\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/micasatucasaibiza.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Can Tomas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/micasatucasaibiza.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/micasatucasaibiza.com\\\/es\\\/\",\"name\":\"Mi Casa Tu Casa Ibiza\",\"description\":\"Special villas. Exclusively managed.\",\"publisher\":{\"@id\":\"https:\\\/\\\/micasatucasaibiza.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/micasatucasaibiza.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/micasatucasaibiza.com\\\/es\\\/#organization\",\"name\":\"Mi Casa Tu Casa Ibiza\",\"url\":\"https:\\\/\\\/micasatucasaibiza.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/micasatucasaibiza.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/micasatucasaibiza.com\\\/wp-content\\\/uploads\\\/logo.gif\",\"contentUrl\":\"https:\\\/\\\/micasatucasaibiza.com\\\/wp-content\\\/uploads\\\/logo.gif\",\"width\":226,\"height\":97,\"caption\":\"Mi Casa Tu Casa Ibiza\"},\"image\":{\"@id\":\"https:\\\/\\\/micasatucasaibiza.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MiCasaTuCasaIbiza\\\/\",\"https:\\\/\\\/www.instagram.com\\\/micasatucasaibiza\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Villa de 3 dormitorios con piscina privada cerca de San Jos\u00e9","description":"Can Tom\u00e1s es una villa rural en alquiler en Ibiza gestionada en exclusiva por Mi Casa Tu casa. Tiene 3 dormitorios, vistas al campo y piscina privada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"\/es\/","og_locale":"es_ES","og_type":"article","og_title":"Villa de 3 dormitorios con piscina privada cerca de San Jos\u00e9","og_description":"Can Tom\u00e1s es una villa rural en alquiler en Ibiza gestionada en exclusiva por Mi Casa Tu casa. Tiene 3 dormitorios, vistas al campo y piscina privada","og_url":"\/es\/","og_site_name":"Mi Casa Tu Casa Ibiza","article_publisher":"https:\/\/www.facebook.com\/MiCasaTuCasaIbiza\/","article_modified_time":"2026-03-03T08:37:25+00:00","og_image":[{"width":2000,"height":1333,"url":"https:\/\/micasatucasaibiza.com\/wp-content\/uploads\/2017\/04\/can-tomas-exterior-dining.jpg","type":"image\/jpeg"}],"twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/micasatucasaibiza.com\/es\/ibiza-rental-villas\/can-tomas\/","url":"\/es\/","name":"Villa de 3 dormitorios con piscina privada cerca de San Jos\u00e9","isPartOf":{"@id":"https:\/\/micasatucasaibiza.com\/es\/#website"},"primaryImageOfPage":{"@id":"\/es\/#primaryimage"},"image":{"@id":"\/#primaryimage"},"thumbnailUrl":"https:\/\/micasatucasaibiza.com\/wp-content\/uploads\/2017\/04\/can-tomas-exterior-dining.jpg","datePublished":"2017-04-17T16:26:12+00:00","dateModified":"2026-03-03T08:37:25+00:00","description":"Can Tom\u00e1s es una villa rural en alquiler en Ibiza gestionada en exclusiva por Mi Casa Tu casa. Tiene 3 dormitorios, vistas al campo y piscina privada","breadcrumb":{"@id":"\/es\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":[["\/es\/"]]}]},{"@type":"ImageObject","inLanguage":"es","@id":"\/es\/#primaryimage","url":"https:\/\/micasatucasaibiza.com\/wp-content\/uploads\/2017\/04\/can-tomas-exterior-dining.jpg","contentUrl":"https:\/\/micasatucasaibiza.com\/wp-content\/uploads\/2017\/04\/can-tomas-exterior-dining.jpg","width":2000,"height":1333,"caption":"Can Tomas Exterior Dining"},{"@type":"BreadcrumbList","@id":"\/es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/micasatucasaibiza.com\/es\/"},{"@type":"ListItem","position":2,"name":"Can Tomas"}]},{"@type":"WebSite","@id":"https:\/\/micasatucasaibiza.com\/es\/#website","url":"https:\/\/micasatucasaibiza.com\/es\/","name":"Mi Casa Tu Casa Ibiza","description":"Special villas. Exclusively managed.","publisher":{"@id":"https:\/\/micasatucasaibiza.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/micasatucasaibiza.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/micasatucasaibiza.com\/es\/#organization","name":"Mi Casa Tu Casa Ibiza","url":"https:\/\/micasatucasaibiza.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/micasatucasaibiza.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/micasatucasaibiza.com\/wp-content\/uploads\/logo.gif","contentUrl":"https:\/\/micasatucasaibiza.com\/wp-content\/uploads\/logo.gif","width":226,"height":97,"caption":"Mi Casa Tu Casa Ibiza"},"image":{"@id":"https:\/\/micasatucasaibiza.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MiCasaTuCasaIbiza\/","https:\/\/www.instagram.com\/micasatucasaibiza\/"]}]}},"_links":{"self":[{"href":"https:\/\/micasatucasaibiza.com\/es\/wp-json\/wp\/v2\/villas\/3458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/micasatucasaibiza.com\/es\/wp-json\/wp\/v2\/villas"}],"about":[{"href":"https:\/\/micasatucasaibiza.com\/es\/wp-json\/wp\/v2\/types\/villas"}],"version-history":[{"count":11,"href":"https:\/\/micasatucasaibiza.com\/es\/wp-json\/wp\/v2\/villas\/3458\/revisions"}],"predecessor-version":[{"id":18356,"href":"https:\/\/micasatucasaibiza.com\/es\/wp-json\/wp\/v2\/villas\/3458\/revisions\/18356"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/micasatucasaibiza.com\/es\/wp-json\/wp\/v2\/media\/17121"}],"wp:attachment":[{"href":"https:\/\/micasatucasaibiza.com\/es\/wp-json\/wp\/v2\/media?parent=3458"}],"wp:term":[{"taxonomy":"areas","embeddable":true,"href":"https:\/\/micasatucasaibiza.com\/es\/wp-json\/wp\/v2\/areas?post=3458"},{"taxonomy":"bedrooms","embeddable":true,"href":"https:\/\/micasatucasaibiza.com\/es\/wp-json\/wp\/v2\/bedrooms?post=3458"},{"taxonomy":"sleeps","embeddable":true,"href":"https:\/\/micasatucasaibiza.com\/es\/wp-json\/wp\/v2\/sleeps?post=3458"},{"taxonomy":"villa_tag","embeddable":true,"href":"https:\/\/micasatucasaibiza.com\/es\/wp-json\/wp\/v2\/villa_tag?post=3458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}